{"id":2628,"date":"2022-08-17T16:20:13","date_gmt":"2022-08-17T15:20:13","guid":{"rendered":"https:\/\/wp.omeuimo.pt\/imoexpansao\/?p=2628"},"modified":"2022-08-17T16:29:24","modified_gmt":"2022-08-17T15:29:24","slug":"imoexpansao-comemora-30o-aniversario","status":"publish","type":"post","link":"https:\/\/wp.omeuimo.pt\/imoexpansao\/imoexpansao-comemora-30o-aniversario\/","title":{"rendered":"Imoexpans\u00e3o comemora 30\u00ba Anivers\u00e1rio"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/3-525-min.jpg\" alt=\"Moradias Figueira da Foz\" width=\"525\" height=\"478\" \/><\/p>\n<p style=\"text-align: justify\">Imoexpans\u00e3o Imobili\u00e1ria da Figueira da Foz, encerrou as Comemora\u00e7\u00f5es do seu 30\u00ba Anivers\u00e1rio, em conjunto com a Magenta, Associa\u00e7\u00e3o dos Artistas pela Arte, que celebrou tamb\u00e9m o seu 19\u00ba Anivers\u00e1rio.<\/p>\n<p style=\"text-align: justify\">Um dos eventos comemorativos decorreu no dia 7 de Agosto, com uma exposi\u00e7\u00e3o de fotografias antigas da Figueira da Foz.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2624\" style=\"padding: 10px\" src=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/2-525-min.jpg\" alt=\"Imobili\u00e1rias Figueira da Foz\" width=\"525\" height=\"350\" srcset=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/2-525-min.jpg 525w, https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/2-525-min-300x200.jpg 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify\">O evento teve mais de uma centena de fotografias expostas, tendo um cariz solid\u00e1rio, sendo a verba angariada com a venda a reverter para a Liga dos Amigos do Hospital Distrital da Figueira da Foz.<\/p>\n<p style=\"text-align: justify\">A exposi\u00e7\u00e3o esteve patente durante um m\u00eas na sede da Magenta, na Pra\u00e7a Lu\u00eds de Albuquerque, junto ao Forte de Santa Catarina, na parte de baixo da Esplanada Silva Guimar\u00e3es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2626\" style=\"padding: 10px\" src=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/4-525-min.jpg\" alt=\"Casas Figueira da Foz\" width=\"525\" height=\"350\" srcset=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/4-525-min.jpg 525w, https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/4-525-min-300x200.jpg 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p style=\"text-align: justify\">O evento comemorativo contou com a presen\u00e7a do Presidente da C\u00e2mara Municipal, Dr. Pedro Santana Lopes, o Presidente da Mesa da Assembleia Municipal, Eng\u00ba Jos\u00e9 Duarte, a Vereadora Dr\u00aa Olga Br\u00e1s e a Presidente da Junta de Freguesia de Buarcos e S\u00e3o Juli\u00e3o, Rosa Baptista.<\/p>\n<p style=\"text-align: justify\">O Dr. Pedro Santana Lopes, no seu discurso, congratulou-se com as duas entidades, mencionando a bonita alian\u00e7a entre o sector imobili\u00e1rio e a arte, que n\u00e3o tendo muito em comum, com vontade, criatividade e imagina\u00e7\u00e3o, podem criar sinergias para que os edif\u00edcios se enquadrem com mais harmonia, na sua zona envolvente.<\/p>\n<p style=\"text-align: justify\">O Sr. Presidente real\u00e7ou o actual dinamismo do sector imobili\u00e1rio, mencionando que o munic\u00edpio, at\u00e9 Julho, j\u00e1 tinha arrecadado, relativamente a receitas de IMT (Imposto Municipal sobre as Transmiss\u00f5es Onerosas de Im\u00f3veis), o valor previsto para todo o ano de 2022, mencionando o contributo dos empres\u00e1rios para que a Figueira esteja na vanguarda, e ainda a sua disponibilidade para ouvir sugest\u00f5es para tornar a Figueira da Foz ainda mais apetec\u00edvel, pois quer no passado, como mostra o t\u00edtulo da exposi\u00e7\u00e3o fotogr\u00e1fica, \u201cFigueira da Foz, Ontem como Hoje, \u00e9 um Encanto\u201d.<br \/>\nPor sua vez, a fundadora da Imoexpans\u00e3o, Ana Machado, falou do passado, passando a palavra ao seu filho e gerente, Ant\u00f3nio Ambr\u00f3sio, que falou do futuro, prometendo continuar a trabalhar seguindo o ADN da Imoexpans\u00e3o, sempre ao servi\u00e7o dos seus clientes, dos Figueirenses e de todos os quantos vivem, ou visitem a Figueira da Foz.<\/p>\n<p style=\"text-align: justify\">Findos os discursos, uma actua\u00e7\u00e3o musical, onde ao piano a voz de Adelaide Sofia brindou os presentes com o Hino da Figueira da Foz e os Parab\u00e9ns \u00e0s aniversariantes.<\/p>\n<p style=\"text-align: justify\">A boa disposi\u00e7\u00e3o prosseguiu com o corte dos bolos de anivers\u00e1rio da Imoexpans\u00e3o e Magenta, brindes e conv\u00edvio entre os presentes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2627\" style=\"padding: 10px\" src=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/5-525-min.jpg\" alt=\"Comprar Casa\" width=\"525\" height=\"339\" srcset=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/5-525-min.jpg 525w, https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-content\/uploads\/sites\/3\/2022\/08\/5-525-min-300x194.jpg 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>Veja estas e outras fotos <a href=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/imoexpansao-comemora-30o-aniversario-2\/\" target=\"_blank\" rel=\"noopener\">aqui<\/a>\u00a0e veja o que saiu nos <a href=\"https:\/\/imoexpansao.pt\/blog\/a-imoexpansao-e-os-media-de-27-02-1992-a-23-03-2011\" target=\"_blank\" rel=\"noopener\">media<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Imoexpans\u00e3o Imobili\u00e1ria da Figueira da Foz, encerrou as Comemora\u00e7\u00f5es do seu 30\u00ba Anivers\u00e1rio, em conjunto com a Magenta, Associa\u00e7\u00e3o dos Artistas pela Arte, que celebrou tamb\u00e9m o seu 19\u00ba Anivers\u00e1rio. Um dos eventos comemorativos decorreu no dia 7 de Agosto, com uma exposi\u00e7\u00e3o de fotografias antigas da Figueira da Foz. O evento teve mais &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/wp.omeuimo.pt\/imoexpansao\/imoexpansao-comemora-30o-aniversario\/\" class=\"more-link\">Continuar a ler <span class=\"screen-reader-text\">&#8220;Imoexpans\u00e3o comemora 30\u00ba Anivers\u00e1rio&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-2628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diversos","category-noticias"],"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/posts\/2628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/comments?post=2628"}],"version-history":[{"count":7,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/posts\/2628\/revisions"}],"predecessor-version":[{"id":2796,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/posts\/2628\/revisions\/2796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/media\/2623"}],"wp:attachment":[{"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/media?parent=2628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/categories?post=2628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.omeuimo.pt\/imoexpansao\/wp-json\/wp\/v2\/tags?post=2628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}